{"id":12668,"date":"2019-10-23T21:54:46","date_gmt":"2019-10-23T19:54:46","guid":{"rendered":"http:\/\/www1.studentenwerk-magdeburg.de\/?post_type=ufaq&#038;p=12668"},"modified":"2024-06-10T14:06:40","modified_gmt":"2024-06-10T13:06:40","slug":"wo-bekomme-ich-den-schluessel-fuer-mein-zimmer","status":"publish","type":"ufaq","link":"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wo-bekomme-ich-den-schluessel-fuer-mein-zimmer\/","title":{"rendered":"Wo bekomme ich den Schl\u00fcssel f\u00fcr mein Zimmer?"},"content":{"rendered":"<div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/en\/wp-json\/wp\/v2\/ufaq\/12668' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-12668-3fHkq2WO6F' data-post_id='12668'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tWo bekomme ich den Schl\u00fcssel f\u00fcr mein Zimmer?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Die Schl\u00fcssel\u00fcbergabe erfolgt am ersten Tag des Mietvertragbeginns. Wenn der Tag auf einen Samstag oder Sonntag f\u00e4llt, ist der darauffolgende Werktag der Tag der Schl\u00fcssel\u00fcbergabe.<\/p>\n<p>Die Schl\u00fcssel bekommen Sie vom <a href=\"\/?page_id=228\">Hausmeister<\/a> im BeratungsCenter (J.-G.-Nathusius-Ring 5) des Studentenwerks ausgeh\u00e4ndigt. Bitte informieren Sie sich \u00fcber die Sprechzeiten.<\/p>\n<p>K\u00f6nnen Sie nicht zu den Sprechzeiten anreisen, k\u00f6nnen Sie bei uns auch eine Vollmacht anfordern oder selbst eine ausstellen und den Schl\u00fcssel von einer beauftragten Person abholen lassen.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-categories'>\n\t\n\tCategory:\n\t\n\t\tEin- und Auszug\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-permalink'>\n\t\n\t<a href='https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wo-bekomme-ich-den-schluessel-fuer-mein-zimmer\/?Display_FAQ=12668'>\n\t\t\n\t\tPermalink\t\t <div class='ewd-ufaq-permalink-image'><\/div> \t\n\t<\/a>\n\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Wo bekomme ich den Schl\u00fcssel f\u00fcr mein Zimmer? Die Schl\u00fcssel\u00fcbergabe erfolgt am ersten Tag des Mietvertragbeginns. Wenn der Tag auf einen Samstag oder Sonntag f\u00e4llt, ist der darauffolgende Werktag der Tag der Schl\u00fcssel\u00fcbergabe. Die Schl\u00fcssel bekommen Sie vom Hausmeister im BeratungsCenter (J.-G.-Nathusius-Ring 5) des Studentenwerks ausgeh\u00e4ndigt. Bitte informieren Sie &hellip; <a href=\"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wo-bekomme-ich-den-schluessel-fuer-mein-zimmer\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[76],"ufaq-tag":[],"class_list":["post-12668","ufaq","type-ufaq","status-publish","hentry","ufaq-category-wohnen-einzug"],"_links":{"self":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq\/12668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/comments?post=12668"}],"wp:attachment":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/media?parent=12668"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-category?post=12668"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-tag?post=12668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}