{"id":12666,"date":"2019-10-23T21:51:43","date_gmt":"2019-10-23T19:51:43","guid":{"rendered":"http:\/\/www1.studentenwerk-magdeburg.de\/?post_type=ufaq&#038;p=12666"},"modified":"2019-11-05T15:51:08","modified_gmt":"2019-11-05T13:51:08","slug":"wann-und-wie-werde-ich-ueber-die-wohnheimplatzvergabe-informiert","status":"publish","type":"ufaq","link":"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wann-und-wie-werde-ich-ueber-die-wohnheimplatzvergabe-informiert\/","title":{"rendered":"Wann und wie werde ich \u00fcber die Wohnheimplatzvergabe informiert?"},"content":{"rendered":"<div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/en\/wp-json\/wp\/v2\/ufaq\/12666' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-12666-0Abq6Rl30c' data-post_id='12666'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tWann und wie werde ich \u00fcber die Wohnheimplatzvergabe informiert?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Die konkrete Wohnheimplatzvergabe beginnt ca. vier bis sechs Wochen vor dem gew\u00fcnschten Einzugstermin. Sobald wir Ihnen einen Wohnheimplatz anbieten k\u00f6nnen, erhalten Sie ein Angebot, bestehend aus Mietvertrag und weiteren Unterlagen, per E-Mail. Innerhalb der vorgegebenen Frist m\u00fcssen Sie die abgeforderten Unterlagen und unterschriftpflichtigen Dokumente an uns per Post zur\u00fcck senden. Studierende, die sich im Ausland aufhalten, k\u00f6nnen die Unterlagen vorab bis zum genannten Termin per Mail senden und die Originale sp\u00e4ter nachreichen. Erhalten wir innerhalb der Frist die vollst\u00e4ndigen Unterlagen nicht zur\u00fcck, erlischt der Anspruch auf diesen Wohnheimplatz und der Antrag wird aus der Warteliste gel\u00f6scht.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-categories'>\n\t\n\tCategory:\n\t\n\t\tWohnheimplatzvergabe\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-permalink'>\n\t\n\t<a href='https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wann-und-wie-werde-ich-ueber-die-wohnheimplatzvergabe-informiert\/?Display_FAQ=12666'>\n\t\t\n\t\tPermalink\t\t <div class='ewd-ufaq-permalink-image'><\/div> \t\n\t<\/a>\n\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Wann und wie werde ich \u00fcber die Wohnheimplatzvergabe informiert? Die konkrete Wohnheimplatzvergabe beginnt ca. vier bis sechs Wochen vor dem gew\u00fcnschten Einzugstermin. Sobald wir Ihnen einen Wohnheimplatz anbieten k\u00f6nnen, erhalten Sie ein Angebot, bestehend aus Mietvertrag und weiteren Unterlagen, per E-Mail. Innerhalb der vorgegebenen Frist m\u00fcssen Sie die abgeforderten &hellip; <a href=\"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wann-und-wie-werde-ich-ueber-die-wohnheimplatzvergabe-informiert\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[75],"ufaq-tag":[],"class_list":["post-12666","ufaq","type-ufaq","status-publish","hentry","ufaq-category-wohnen-vergabe"],"_links":{"self":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq\/12666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/comments?post=12666"}],"wp:attachment":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/media?parent=12666"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-category?post=12666"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-tag?post=12666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}