{"id":12664,"date":"2019-10-23T21:47:34","date_gmt":"2019-10-23T19:47:34","guid":{"rendered":"http:\/\/www1.studentenwerk-magdeburg.de\/?post_type=ufaq&#038;p=12664"},"modified":"2019-10-23T21:47:34","modified_gmt":"2019-10-23T19:47:34","slug":"wie-stehen-die-chancen-einen-wohnplatz-zu-erhalten","status":"publish","type":"ufaq","link":"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wie-stehen-die-chancen-einen-wohnplatz-zu-erhalten\/","title":{"rendered":"Wie stehen die Chancen, einen Wohnplatz zu erhalten?"},"content":{"rendered":"<div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/en\/wp-json\/wp\/v2\/ufaq\/12664' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-12664-cvguqpkRG5' data-post_id='12664'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tWie stehen die Chancen, einen Wohnplatz zu erhalten?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Die gr\u00f6\u00dfte Nachfrage nach Wohnraum ist zu den Zeiten des Semesterbeginns. Da die Wohnheimplatzvergabe in Reihenfolge des Eingangs der Antr\u00e4ge erfolgt, ist eine fr\u00fchzeitige Antragstellung sinnvoll (f\u00fcr Studienanf\u00e4nger gilt: Antr\u00e4ge k\u00f6nnen maximal 6 Monate vor gew\u00fcnschtem Einzugstermin eingereicht werden).<br \/>\nBei der Antragstellung haben Sie die M\u00f6glichkeit, W\u00fcnsche zum Wohnheimplatz anzugeben (Angabe des bevorzugten Wohnheimes, M\u00f6blierung\u2026). Je flexibler Sie in Ihren W\u00fcnschen sind, desto gr\u00f6\u00dfer ist die Wahrscheinlichkeit auf einen Wohnheimplatz.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-categories'>\n\t\n\tCategory:\n\t\n\t\tWohnheimplatzvergabe\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-permalink'>\n\t\n\t<a href='https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wie-stehen-die-chancen-einen-wohnplatz-zu-erhalten\/?Display_FAQ=12664'>\n\t\t\n\t\tPermalink\t\t <div class='ewd-ufaq-permalink-image'><\/div> \t\n\t<\/a>\n\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Wie stehen die Chancen, einen Wohnplatz zu erhalten? Die gr\u00f6\u00dfte Nachfrage nach Wohnraum ist zu den Zeiten des Semesterbeginns. Da die Wohnheimplatzvergabe in Reihenfolge des Eingangs der Antr\u00e4ge erfolgt, ist eine fr\u00fchzeitige Antragstellung sinnvoll (f\u00fcr Studienanf\u00e4nger gilt: Antr\u00e4ge k\u00f6nnen maximal 6 Monate vor gew\u00fcnschtem Einzugstermin eingereicht werden). Bei der &hellip; <a href=\"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wie-stehen-die-chancen-einen-wohnplatz-zu-erhalten\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[75],"ufaq-tag":[],"class_list":["post-12664","ufaq","type-ufaq","status-publish","hentry","ufaq-category-wohnen-vergabe"],"_links":{"self":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq\/12664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/comments?post=12664"}],"wp:attachment":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/media?parent=12664"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-category?post=12664"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-tag?post=12664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}