{"id":12638,"date":"2019-10-23T13:03:40","date_gmt":"2019-10-23T11:03:40","guid":{"rendered":"http:\/\/www1.studentenwerk-magdeburg.de\/?post_type=ufaq&#038;p=12638"},"modified":"2019-10-23T13:03:40","modified_gmt":"2019-10-23T11:03:40","slug":"wann-kann-ich-mich-fuer-einen-wohnheimplatz-bewerben","status":"publish","type":"ufaq","link":"https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wann-kann-ich-mich-fuer-einen-wohnheimplatz-bewerben\/","title":{"rendered":"Wann kann ich mich f\u00fcr einen Wohnheimplatz bewerben?"},"content":{"rendered":"<div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/en\/wp-json\/wp\/v2\/ufaq\/12638' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-12638-BokS7MQjFZ' data-post_id='12638'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tWann kann ich mich f\u00fcr einen Wohnheimplatz bewerben?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Studienanf\u00e4nger k\u00f6nnen einen Antrag auf einen Wohnheimplatz ein Semester vor beabsichtigtem Studienbeginn stellen. Ansonsten gibt es keine festen Fristen.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-categories'>\n\t\n\tCategory:\n\t\n\t\tAntragstellung\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-permalink'>\n\t\n\t<a href='https:\/\/www.studentenwerk-magdeburg.de\/en\/ufaqs\/wann-kann-ich-mich-fuer-einen-wohnheimplatz-bewerben\/?Display_FAQ=12638'>\n\t\t\n\t\tPermalink\t\t <div class='ewd-ufaq-permalink-image'><\/div> \t\n\t<\/a>\n\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Wann kann ich mich f\u00fcr einen Wohnheimplatz bewerben? Studienanf\u00e4nger k\u00f6nnen einen Antrag auf einen Wohnheimplatz ein Semester vor beabsichtigtem Studienbeginn stellen. Ansonsten gibt es keine festen Fristen. Category: Antragstellung Permalink<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[73],"ufaq-tag":[],"class_list":["post-12638","ufaq","type-ufaq","status-publish","hentry","ufaq-category-wohnen-antrag"],"_links":{"self":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq\/12638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/comments?post=12638"}],"wp:attachment":[{"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/media?parent=12638"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-category?post=12638"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.studentenwerk-magdeburg.de\/en\/wp-json\/wp\/v2\/ufaq-tag?post=12638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}